{"id":84,"date":"2005-04-04T22:48:33","date_gmt":"2005-04-04T21:48:33","guid":{"rendered":"http:\/\/www.umweltnetz.ch\/content\/johannes-paul-ii-ein-grosser-papst-aber\/"},"modified":"2008-11-08T09:42:17","modified_gmt":"2008-11-08T08:42:17","slug":"johannes-paul-ii-ein-grosser-papst-aber","status":"publish","type":"post","link":"https:\/\/www.umweltnetz.ch\/content\/johannes-paul-ii-ein-grosser-papst-aber","title":{"rendered":"Johannes Paul II: Ein grosser Papst! Aber&#8230;"},"content":{"rendered":"<p>Im Vatikanstaat, sei es im Petersdom, sei es in den Vatikanischen G&auml;rten oder im Vatikanischen Museum, trifft die BesucherIn auf Schritt und Tritt auf Zeichen der langen Geschichte des Papsttums. Die P&auml;pste haben auf Schildchen festhalten lassen, was sie an sichtbaren Werken haben erstellen lassen w&auml;hrend ihres Pontifikates. Diese Schildchen sind ein Symbol einerseits f&uuml;r die Verg&auml;nglcihkeit, andererseits eine Ahnung von Unendlichkeit. P&auml;pste, deren Zeit und ZeitgenossInnen l&auml;ngst vergangen sind, haben alle mitgebaut an diesem Vatikanstaat, der als Gebilde von Menschhand gebaut f&uuml;r alle Ewigkeiten erscheint.    <!--more--><\/p>\n<p>Zeichen hinterlassen P&auml;pste nicht nur durch Bauwerke, sondern auch durch ihre Aussagen und Festsetzungen zum religi&ouml;sen und allt&auml;glichen Leben der Menschen, die sich als Teil der r&ouml;misch-katholischen Kirche verstehen.<\/p>\n<p>Papst Johannes Paul II hat baulich einige Spuren hinterlassen im Vatikanstaat &#8211; er hat aber auch in seinem langen Pontifikat eine ganze Reihe von Schriften verfasst, die sich sehr konkret auf die Kirche und die Gl&auml;ubigen auswirken. Papst Johannes Paul II hat mit viel Ausdauer und lautstark sich f&uuml;r den Frieden eingesetzt. Und er hat beeindruckt durch sein Charisma, seine Klugheit und seine Gl&auml;ubigkeit.<\/p>\n<p>Pr&auml;gend auch seine Auffasung &uuml;ber die menschliche Verpflichtung, sich quasi bis zum letzten Atemzug einzusetzen f&uuml;r die Aufgaben und Pflichten, die Menschen durch ihr Menschsein zu erf&uuml;llen haben. Durch seine langdauernde Krankheit hat er gezeigt, dass auch Leiden Teil des menschlichen Lebens, der menschlichen Verpflichtung ist. Es gibt aber auch einen Zeitpunkt, von dieser Erde zu gehen, auch wenn die Aufgabe noch so gross und noch nicht zu Ende gebracht ist: eine medizinisch-technische Lebensver&auml;ngerung um jeden Preis braucht es nicht!<\/p>\n<p>*** *** *** ***<\/p>\n<p>Auch bei einem grossen Papst gibt es &#8222;Aber&#8220;! Dazu geh&ouml;ren Entscheide zu dogmatischen Themen, zu Themen des allt&auml;glichen Lebens &#8211; die nicht mehr damit erkl&auml;rt werden k&ouml;nnen, dass eine so alte Institution wie die katholische Kirche halt eben konservativ entscheide. Beispielsweise der Pflichtz&ouml;libat, die Rolle der Frau in der Kirche oder Fragen der Sexualit&auml;t wurden durch den Papst nicht wirklich angegangen, sondern tabuisiert. Der Papst hat sich eigentlich jeweils nur dazu ge&auml;ussert, dass es einen Glauben an Gott gibt, nicht aber, was diesen Glauben inhaltlich ausmacht und welche Auswirkungen dieser Glaube auf das Alltagsleben hat.<\/p>\n<p>Wer sich mit derartigen Fragen kritisch und nicht im Sinne der tabuisierten Haltung des Papstes auseinandersetzte, hatte und hat es schwer in der katholischen Kirche, wie beispielsweise Prof. Hans K&uuml;ng (Entzug der Lehrerlaubnis 1979). Es ist eigenartig, dass ein Papst, welcher dem friedlichen Umgang mit den Menschen untereinander ein derart grosses Gewicht zukommen l&auml;sst, ausgerechnet kirchenintern derartige zumindest psychische Gewalt angewendet hat. Der Entzug der Lehrerlaubnis ist ein sehr harter Eingriff in das Wirken einer Person, die mit vollem Engagement, aufbauend auf dem christlichen Glauben, sich daf&uuml;r einsetzt, Glaubensgrunds&auml;tze zu vermitteln, auch als Basis f&uuml;r ein segensreiches Wirken innerhalb der Kirche.<\/p>\n<p>Am Beispiel von Hans K&uuml;ng l&auml;sst sich zeigen, wie dramatisch sich dieser harte und nicht zu rechtfertigende Eingriff sowohl auf die Weltpolitik als auch die Glaubw&uuml;rdigkeit der Glaubensgemeinschaften und ihrer Kirchen auswirkt.<\/p>\n<p>Hans K&uuml;ng ist einer der wichtigen F&ouml;rderer und Botschafter des Weltethos (<a href=\"http:\/\/www.weltethos.org\/\" target=\"_blank\">Details<\/a>). Hans K&uuml;ng hat 1990 festgehalten:<\/p>\n<p><i>Die Religionen  der Welt k&ouml;nnen nur dann einen Beitrag zum Frieden der Menschheit leisten, wenn sie sich auf das ihnen jetzt schon Gemeinsame im Ethos besinnen: auf einen Grundkonsens bez&uuml;glich bestehender verbindender Werte, unverr&uuml;ckbarer Massst&auml;be und pers&ouml;nlicher Grundhaltungen.<\/i><\/p>\n<p>1993 wurde von verschiedenen Religionen (Bahai, Brahma Kumaris, Buddhismus, Christentum, Eingeborenen-Religionen, Hinduismus, Jainismus, Judentum, Islam, Neu-Heiden, Sikhs, Taoisten, Theosophen, Zoroastrier, Interreligi&ouml;se Organisationen) eine &#8222;Erkl&auml;rung zum Weltethos&#8220; verabschiedet.<\/p>\n<p><i>Mit dieser Erkl&auml;rung haben sich erstmals Vertreter aller  Religionen &uuml;ber Prinzipien eines Weltethos verst&auml;ndigt und sich auf vier unverr&uuml;ckbare  Weisungen verpflichtet, die im einzelnen konkretisiert werden:<\/p>\n<ul>\n<li>Verpflichtung auf eine Kultur der Gewaltlosigkeit und der Ehrfurcht vor allem Leben.<\/li>\n<li>Verpflichtung auf eine Kultur der Solidarit&auml;t und eine gerechte Wirtschaftsordnung.<\/li>\n<li>Verpflichtung auf eine Kultur der Toleranz und ein Leben in Wahrhaftigkeit.<\/li>\n<li>Verpflichtung auf eine Kultur der Gleichberechtigung und die Partnerschaft von Mann und Frau.<\/li>\n<\/ul>\n<p><\/i><\/p>\n<p>Wenn der Weltethos bereits eine gr&ouml;ssere Bedeutung h&auml;tte &#8211; und das hat der Papst mit der &Auml;chtung von Prof. Hans K&uuml;ng wirkungsvoll verhindert &#8211; h&auml;tte vor dem Irak-Krieg 2003 nicht die absurde Situation entstehen k&ouml;nnen, dass<\/p>\n<ul>\n<li>der Papst mit Bezug auf (seinen) Gott auf eine friedliche L&ouml;sung gedr&auml;ngt h&auml;tte,<\/li>\n<li>der amerkanische Pr&auml;sident George W. Bush den Krieg mit Bezug auf (seinen) Gott begr&uuml;ndete, und<\/li>\n<li>der damalige irakische Staatschef sein Verhalten ebenfalls mit Bezug auf (seinen) Gott rechtfertigte.<\/li>\n<\/ul>\n<p>Es ist ohne Wenn und Aber festzuhalten, dass die p&auml;pstliche Position f&uuml;r eine friedliche L&ouml;sung mit dem Weltethos vereinbar ist, nicht aber die der jeweiligen Akteure. Der Papst ist allerdings durch seine Haltung vor allem gegen innen, seine Position durch einen Unfehlbarkeits-Anspruch vertreten zu wollen, erheblich vom Weltethos abgewichen &#8211; und reduziert sich dadurch auf einen jener vielen &#8222;Global Players&#8220;, die sich auf ihre &#8222;Macht&#8220; berufen, was letztlich eine Gewalt-Aus&uuml;bung darstellt. Mit der umfassenden Berufung auf einen &#8222;reinen&#8220; Weltethos w&auml;re es dem Papst allenfalls gelungen, sowohl Bush wie den irakischen Staatschef von ihren vollst&auml;ndig vom Weltethos abweichenden Haltungen abr&uuml;cken zu lassen und vor allen jegliche Formen der religi&ouml;sen Rechtfertigung des eigenen gewaltt&auml;tigen Verhaltens unm&ouml;glich zu machen.<\/p>\n<p>Nicht nur der Papst, alle Menschen auf dieser Erde haben die Verantwortung, daf&uuml;r zu sorgen, dass auf dieser Erde die oben genannten vier unverr&uuml;ckbaren Weisungen verpflichtend werden!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Im Vatikanstaat, sei es im Petersdom, sei es in den Vatikanischen G&auml;rten oder im Vatikanischen Museum, trifft die BesucherIn auf Schritt und Tritt auf Zeichen der langen Geschichte des Papsttums. Die P&auml;pste haben auf Schildchen festhalten lassen, was sie an sichtbaren Werken haben erstellen lassen w&auml;hrend ihres Pontifikates. Diese Schildchen sind ein Symbol einerseits f&uuml;r &hellip; <a href=\"https:\/\/www.umweltnetz.ch\/content\/johannes-paul-ii-ein-grosser-papst-aber\" class=\"more-link\"><span class=\"screen-reader-text\">\u201eJohannes Paul II: Ein grosser Papst! Aber&#8230;\u201c <\/span>weiterlesen<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[257,256,252],"class_list":["post-84","post","type-post","status-publish","format-standard","hentry","category-allgemein","tag-ethik","tag-frieden","tag-weltethos"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Toni W. P\u00fcntener\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.umweltnetz.ch\/content\/johannes-paul-ii-ein-grosser-papst-aber\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"umweltnetz.ch | Umwelt und Politik - ein Internet-Angebot von Toni W. P\u00fcntener\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Johannes Paul II: Ein grosser Papst! Aber\u2026 | umweltnetz.ch\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.umweltnetz.ch\/content\/johannes-paul-ii-ein-grosser-papst-aber\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2005-04-04T21:48:33+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2008-11-08T08:42:17+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Johannes Paul II: Ein grosser Papst! Aber\u2026 | umweltnetz.ch\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.umweltnetz.ch\\\/content\\\/johannes-paul-ii-ein-grosser-papst-aber#article\",\"name\":\"Johannes Paul II: Ein grosser Papst! Aber\\u2026 | umweltnetz.ch\",\"headline\":\"Johannes Paul II: Ein grosser Papst! Aber&#8230;\",\"author\":{\"@id\":\"https:\\\/\\\/www.umweltnetz.ch\\\/content\\\/author\\\/twp#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.umweltnetz.ch\\\/content\\\/#organization\"},\"datePublished\":\"2005-04-04T22:48:33+02:00\",\"dateModified\":\"2008-11-08T09:42:17+01:00\",\"inLanguage\":\"de-DE\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.umweltnetz.ch\\\/content\\\/johannes-paul-ii-ein-grosser-papst-aber#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.umweltnetz.ch\\\/content\\\/johannes-paul-ii-ein-grosser-papst-aber#webpage\"},\"articleSection\":\"Allgemein, Ethik, Frieden, Weltethos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.umweltnetz.ch\\\/content\\\/johannes-paul-ii-ein-grosser-papst-aber#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.umweltnetz.ch\\\/content#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.umweltnetz.ch\\\/content\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.umweltnetz.ch\\\/content\\\/category\\\/allgemein#listItem\",\"name\":\"Allgemein\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.umweltnetz.ch\\\/content\\\/category\\\/allgemein#listItem\",\"position\":2,\"name\":\"Allgemein\",\"item\":\"https:\\\/\\\/www.umweltnetz.ch\\\/content\\\/category\\\/allgemein\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.umweltnetz.ch\\\/content\\\/johannes-paul-ii-ein-grosser-papst-aber#listItem\",\"name\":\"Johannes Paul II: Ein grosser Papst! Aber&#8230;\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.umweltnetz.ch\\\/content#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.umweltnetz.ch\\\/content\\\/johannes-paul-ii-ein-grosser-papst-aber#listItem\",\"position\":3,\"name\":\"Johannes Paul II: Ein grosser Papst! Aber&#8230;\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.umweltnetz.ch\\\/content\\\/category\\\/allgemein#listItem\",\"name\":\"Allgemein\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.umweltnetz.ch\\\/content\\\/#organization\",\"name\":\"umweltnetz.ch\",\"description\":\"Umwelt und Politik - ein Internet-Angebot von Toni W. P\\u00fcntener\",\"url\":\"https:\\\/\\\/www.umweltnetz.ch\\\/content\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.umweltnetz.ch\\\/content\\\/author\\\/twp#author\",\"url\":\"https:\\\/\\\/www.umweltnetz.ch\\\/content\\\/author\\\/twp\",\"name\":\"Toni W. P\\u00fcntener\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.umweltnetz.ch\\\/content\\\/johannes-paul-ii-ein-grosser-papst-aber#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4b38790bfc673702bc7f3864264936e7baf1594c44260587ec4964490a262b9?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Toni W. P\\u00fcntener\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.umweltnetz.ch\\\/content\\\/johannes-paul-ii-ein-grosser-papst-aber#webpage\",\"url\":\"https:\\\/\\\/www.umweltnetz.ch\\\/content\\\/johannes-paul-ii-ein-grosser-papst-aber\",\"name\":\"Johannes Paul II: Ein grosser Papst! Aber\\u2026 | umweltnetz.ch\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.umweltnetz.ch\\\/content\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.umweltnetz.ch\\\/content\\\/johannes-paul-ii-ein-grosser-papst-aber#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.umweltnetz.ch\\\/content\\\/author\\\/twp#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.umweltnetz.ch\\\/content\\\/author\\\/twp#author\"},\"datePublished\":\"2005-04-04T22:48:33+02:00\",\"dateModified\":\"2008-11-08T09:42:17+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.umweltnetz.ch\\\/content\\\/#website\",\"url\":\"https:\\\/\\\/www.umweltnetz.ch\\\/content\\\/\",\"name\":\"umweltnetz.ch\",\"description\":\"Umwelt und Politik - ein Internet-Angebot von Toni W. P\\u00fcntener\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.umweltnetz.ch\\\/content\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Johannes Paul II: Ein grosser Papst! Aber\u2026 | umweltnetz.ch","description":"","canonical_url":"https:\/\/www.umweltnetz.ch\/content\/johannes-paul-ii-ein-grosser-papst-aber","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.umweltnetz.ch\/content\/johannes-paul-ii-ein-grosser-papst-aber#article","name":"Johannes Paul II: Ein grosser Papst! Aber\u2026 | umweltnetz.ch","headline":"Johannes Paul II: Ein grosser Papst! Aber&#8230;","author":{"@id":"https:\/\/www.umweltnetz.ch\/content\/author\/twp#author"},"publisher":{"@id":"https:\/\/www.umweltnetz.ch\/content\/#organization"},"datePublished":"2005-04-04T22:48:33+02:00","dateModified":"2008-11-08T09:42:17+01:00","inLanguage":"de-DE","mainEntityOfPage":{"@id":"https:\/\/www.umweltnetz.ch\/content\/johannes-paul-ii-ein-grosser-papst-aber#webpage"},"isPartOf":{"@id":"https:\/\/www.umweltnetz.ch\/content\/johannes-paul-ii-ein-grosser-papst-aber#webpage"},"articleSection":"Allgemein, Ethik, Frieden, Weltethos"},{"@type":"BreadcrumbList","@id":"https:\/\/www.umweltnetz.ch\/content\/johannes-paul-ii-ein-grosser-papst-aber#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.umweltnetz.ch\/content#listItem","position":1,"name":"Home","item":"https:\/\/www.umweltnetz.ch\/content","nextItem":{"@type":"ListItem","@id":"https:\/\/www.umweltnetz.ch\/content\/category\/allgemein#listItem","name":"Allgemein"}},{"@type":"ListItem","@id":"https:\/\/www.umweltnetz.ch\/content\/category\/allgemein#listItem","position":2,"name":"Allgemein","item":"https:\/\/www.umweltnetz.ch\/content\/category\/allgemein","nextItem":{"@type":"ListItem","@id":"https:\/\/www.umweltnetz.ch\/content\/johannes-paul-ii-ein-grosser-papst-aber#listItem","name":"Johannes Paul II: Ein grosser Papst! Aber&#8230;"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.umweltnetz.ch\/content#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.umweltnetz.ch\/content\/johannes-paul-ii-ein-grosser-papst-aber#listItem","position":3,"name":"Johannes Paul II: Ein grosser Papst! Aber&#8230;","previousItem":{"@type":"ListItem","@id":"https:\/\/www.umweltnetz.ch\/content\/category\/allgemein#listItem","name":"Allgemein"}}]},{"@type":"Organization","@id":"https:\/\/www.umweltnetz.ch\/content\/#organization","name":"umweltnetz.ch","description":"Umwelt und Politik - ein Internet-Angebot von Toni W. P\u00fcntener","url":"https:\/\/www.umweltnetz.ch\/content\/"},{"@type":"Person","@id":"https:\/\/www.umweltnetz.ch\/content\/author\/twp#author","url":"https:\/\/www.umweltnetz.ch\/content\/author\/twp","name":"Toni W. P\u00fcntener","image":{"@type":"ImageObject","@id":"https:\/\/www.umweltnetz.ch\/content\/johannes-paul-ii-ein-grosser-papst-aber#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/b4b38790bfc673702bc7f3864264936e7baf1594c44260587ec4964490a262b9?s=96&d=mm&r=g","width":96,"height":96,"caption":"Toni W. P\u00fcntener"}},{"@type":"WebPage","@id":"https:\/\/www.umweltnetz.ch\/content\/johannes-paul-ii-ein-grosser-papst-aber#webpage","url":"https:\/\/www.umweltnetz.ch\/content\/johannes-paul-ii-ein-grosser-papst-aber","name":"Johannes Paul II: Ein grosser Papst! Aber\u2026 | umweltnetz.ch","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/www.umweltnetz.ch\/content\/#website"},"breadcrumb":{"@id":"https:\/\/www.umweltnetz.ch\/content\/johannes-paul-ii-ein-grosser-papst-aber#breadcrumblist"},"author":{"@id":"https:\/\/www.umweltnetz.ch\/content\/author\/twp#author"},"creator":{"@id":"https:\/\/www.umweltnetz.ch\/content\/author\/twp#author"},"datePublished":"2005-04-04T22:48:33+02:00","dateModified":"2008-11-08T09:42:17+01:00"},{"@type":"WebSite","@id":"https:\/\/www.umweltnetz.ch\/content\/#website","url":"https:\/\/www.umweltnetz.ch\/content\/","name":"umweltnetz.ch","description":"Umwelt und Politik - ein Internet-Angebot von Toni W. P\u00fcntener","inLanguage":"de-DE","publisher":{"@id":"https:\/\/www.umweltnetz.ch\/content\/#organization"}}]},"og:locale":"de_DE","og:site_name":"umweltnetz.ch | Umwelt und Politik - ein Internet-Angebot von Toni W. P\u00fcntener","og:type":"article","og:title":"Johannes Paul II: Ein grosser Papst! Aber\u2026 | umweltnetz.ch","og:url":"https:\/\/www.umweltnetz.ch\/content\/johannes-paul-ii-ein-grosser-papst-aber","article:published_time":"2005-04-04T21:48:33+00:00","article:modified_time":"2008-11-08T08:42:17+00:00","twitter:card":"summary","twitter:title":"Johannes Paul II: Ein grosser Papst! Aber\u2026 | umweltnetz.ch"},"aioseo_meta_data":{"post_id":"84","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2020-12-21 15:13:19","updated":"2025-06-03 19:31:22","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.umweltnetz.ch\/content\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.umweltnetz.ch\/content\/category\/allgemein\" title=\"Allgemein\">Allgemein<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tJohannes Paul II: Ein grosser Papst! Aber\u2026\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.umweltnetz.ch\/content"},{"label":"Allgemein","link":"https:\/\/www.umweltnetz.ch\/content\/category\/allgemein"},{"label":"Johannes Paul II: Ein grosser Papst! Aber&#8230;","link":"https:\/\/www.umweltnetz.ch\/content\/johannes-paul-ii-ein-grosser-papst-aber"}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.umweltnetz.ch\/content\/wp-json\/wp\/v2\/posts\/84","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.umweltnetz.ch\/content\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.umweltnetz.ch\/content\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.umweltnetz.ch\/content\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.umweltnetz.ch\/content\/wp-json\/wp\/v2\/comments?post=84"}],"version-history":[{"count":1,"href":"https:\/\/www.umweltnetz.ch\/content\/wp-json\/wp\/v2\/posts\/84\/revisions"}],"predecessor-version":[{"id":316,"href":"https:\/\/www.umweltnetz.ch\/content\/wp-json\/wp\/v2\/posts\/84\/revisions\/316"}],"wp:attachment":[{"href":"https:\/\/www.umweltnetz.ch\/content\/wp-json\/wp\/v2\/media?parent=84"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.umweltnetz.ch\/content\/wp-json\/wp\/v2\/categories?post=84"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.umweltnetz.ch\/content\/wp-json\/wp\/v2\/tags?post=84"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}